{"id":11818,"date":"2021-05-13T14:53:18","date_gmt":"2021-05-13T19:53:18","guid":{"rendered":"https:\/\/completewedo.com\/rochester-new\/?p=11818"},"modified":"2021-05-13T14:53:18","modified_gmt":"2021-05-13T19:53:18","slug":"brittany-sheas-med-city-engagement-session","status":"publish","type":"post","link":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/","title":{"rendered":"Brittany + Shea&#8217;s Med City Engagement Session"},"content":{"rendered":"<p>Engagement sessions are such an amazing opportunity for us to get to know our couples while they&#8217;re still planning their weddings. This particular engagement session was incredible! Everything lined up from the weather to the setting and to say we got lucky with how things turned out is an understatement!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Engagement sessions are such an amazing opportunity for us to get to know our couples while they&#8217;re still planning their weddings. This particular engagement session was incredible! Everything lined up from the weather to the setting and to say we got lucky with how things turned out is an understatement!<\/p>\n","protected":false},"author":73,"featured_media":11829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,11],"tags":[],"class_list":["post-11818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration","category-weddings-engagements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brittany + Shea&#039;s Med City Engagement Session in Rochester, MN<\/title>\n<meta name=\"description\" content=\"We had so much fun taking these photos during Brittany and Shea&#039;s Med City engagement session. Take a look at some of our favorites!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brittany + Shea&#039;s Med City Engagement Session in Rochester, MN\" \/>\n<meta property=\"og:description\" content=\"We had so much fun taking these photos during Brittany and Shea&#039;s Med City engagement session. Take a look at some of our favorites!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Rochester\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompleteRochester\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-13T19:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2021\/05\/Ealy_AR-9561.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"completemarketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"completemarketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brittany + Shea's Med City Engagement Session in Rochester, MN","description":"We had so much fun taking these photos during Brittany and Shea's Med City engagement session. Take a look at some of our favorites!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/","og_locale":"en_US","og_type":"article","og_title":"Brittany + Shea's Med City Engagement Session in Rochester, MN","og_description":"We had so much fun taking these photos during Brittany and Shea's Med City engagement session. Take a look at some of our favorites!","og_url":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/","og_site_name":"Complete Weddings + Events Rochester","article_publisher":"https:\/\/www.facebook.com\/CompleteRochester\/","article_published_time":"2021-05-13T19:53:18+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2021\/05\/Ealy_AR-9561.jpg","type":"image\/jpeg"}],"author":"completemarketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"completemarketing","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/#article","isPartOf":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/"},"author":{"name":"completemarketing","@id":"https:\/\/completewedo.com\/rochester\/#\/schema\/person\/573f73cefcb0d1be216716edc2c246d3"},"headline":"Brittany + Shea&#8217;s Med City Engagement Session","datePublished":"2021-05-13T19:53:18+00:00","mainEntityOfPage":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/"},"wordCount":58,"image":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2021\/05\/Ealy_AR-9561.jpg","articleSection":["Inspiration","Weddings &amp; Engagements"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/","url":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/","name":"Brittany + Shea's Med City Engagement Session in Rochester, MN","isPartOf":{"@id":"https:\/\/completewedo.com\/rochester\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2021\/05\/Ealy_AR-9561.jpg","datePublished":"2021-05-13T19:53:18+00:00","author":{"@id":"https:\/\/completewedo.com\/rochester\/#\/schema\/person\/573f73cefcb0d1be216716edc2c246d3"},"description":"We had so much fun taking these photos during Brittany and Shea's Med City engagement session. Take a look at some of our favorites!","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/rochester\/blog\/brittany-sheas-med-city-engagement-session\/#primaryimage","url":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2021\/05\/Ealy_AR-9561.jpg","contentUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2021\/05\/Ealy_AR-9561.jpg","width":1000,"height":666,"caption":"Bride and groom engagement photo by a Rochester, MN lake Brittany + Shea's Med City Engagement Session"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/rochester\/#website","url":"https:\/\/completewedo.com\/rochester\/","name":"Complete Weddings + Events Rochester","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/rochester\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/completewedo.com\/rochester\/#\/schema\/person\/573f73cefcb0d1be216716edc2c246d3","name":"completemarketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/fba7e6c48d83ba0d1a45b7a66ae2b486380f1f16d577b9755f1b41d234cd2991?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fba7e6c48d83ba0d1a45b7a66ae2b486380f1f16d577b9755f1b41d234cd2991?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fba7e6c48d83ba0d1a45b7a66ae2b486380f1f16d577b9755f1b41d234cd2991?s=96&d=mm&r=g","caption":"completemarketing"},"url":"https:\/\/completewedo.com\/rochester\/blog\/author\/completemarketing\/"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts\/11818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/comments?post=11818"}],"version-history":[{"count":7,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts\/11818\/revisions"}],"predecessor-version":[{"id":11847,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts\/11818\/revisions\/11847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/media\/11829"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/media?parent=11818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/categories?post=11818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/tags?post=11818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}