{"id":10728,"date":"2019-11-20T15:16:27","date_gmt":"2019-11-20T15:16:27","guid":{"rendered":"https:\/\/completewedo.com\/rochester-new\/?p=10728"},"modified":"2019-12-16T18:09:17","modified_gmt":"2019-12-16T18:09:17","slug":"wedding-altar-inspiration-for-every-bride-to-be","status":"publish","type":"post","link":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/","title":{"rendered":"Wedding Altar Inspiration For Every Bride-to-Be"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":73,"featured_media":10740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wedding Altar Inspiration | Complete Weddings + Events in Rochester<\/title>\n<meta name=\"description\" content=\"From bold flowers to crystal chandeliers and greenery galore, the possibilities for a stunning wedding altar inspiration are truly endless.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wedding Altar Inspiration | Complete Weddings + Events in Rochester\" \/>\n<meta property=\"og:description\" content=\"From bold flowers to crystal chandeliers and greenery galore, the possibilities for a stunning wedding altar inspiration are truly endless.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Rochester\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompleteRochester\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-20T15:16:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-16T18:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/11\/dsa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"completemarketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"completemarketing\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wedding Altar Inspiration | Complete Weddings + Events in Rochester","description":"From bold flowers to crystal chandeliers and greenery galore, the possibilities for a stunning wedding altar inspiration are truly endless.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/","og_locale":"en_US","og_type":"article","og_title":"Wedding Altar Inspiration | Complete Weddings + Events in Rochester","og_description":"From bold flowers to crystal chandeliers and greenery galore, the possibilities for a stunning wedding altar inspiration are truly endless.","og_url":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/","og_site_name":"Complete Weddings + Events Rochester","article_publisher":"https:\/\/www.facebook.com\/CompleteRochester\/","article_published_time":"2019-11-20T15:16:27+00:00","article_modified_time":"2019-12-16T18:09:17+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/11\/dsa.jpg","type":"image\/jpeg"}],"author":"completemarketing","twitter_card":"summary_large_image","twitter_misc":{"Written by":"completemarketing"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/#article","isPartOf":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/"},"author":{"name":"completemarketing","@id":"https:\/\/completewedo.com\/rochester\/#\/schema\/person\/573f73cefcb0d1be216716edc2c246d3"},"headline":"Wedding Altar Inspiration For Every Bride-to-Be","datePublished":"2019-11-20T15:16:27+00:00","dateModified":"2019-12-16T18:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/"},"wordCount":6,"image":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/11\/dsa.jpg","articleSection":["Inspiration"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/","url":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/","name":"Wedding Altar Inspiration | Complete Weddings + Events in Rochester","isPartOf":{"@id":"https:\/\/completewedo.com\/rochester\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/11\/dsa.jpg","datePublished":"2019-11-20T15:16:27+00:00","dateModified":"2019-12-16T18:09:17+00:00","author":{"@id":"https:\/\/completewedo.com\/rochester\/#\/schema\/person\/573f73cefcb0d1be216716edc2c246d3"},"description":"From bold flowers to crystal chandeliers and greenery galore, the possibilities for a stunning wedding altar inspiration are truly endless.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/rochester\/blog\/wedding-altar-inspiration-for-every-bride-to-be\/#primaryimage","url":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/11\/dsa.jpg","contentUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/11\/dsa.jpg","width":1000,"height":667,"caption":"Wedding Altar Inspiration"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/rochester\/#website","url":"https:\/\/completewedo.com\/rochester\/","name":"Complete Weddings + Events Rochester","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/rochester\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/completewedo.com\/rochester\/#\/schema\/person\/573f73cefcb0d1be216716edc2c246d3","name":"completemarketing","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/fba7e6c48d83ba0d1a45b7a66ae2b486380f1f16d577b9755f1b41d234cd2991?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fba7e6c48d83ba0d1a45b7a66ae2b486380f1f16d577b9755f1b41d234cd2991?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fba7e6c48d83ba0d1a45b7a66ae2b486380f1f16d577b9755f1b41d234cd2991?s=96&d=mm&r=g","caption":"completemarketing"},"url":"https:\/\/completewedo.com\/rochester\/blog\/author\/completemarketing\/"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts\/10728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/comments?post=10728"}],"version-history":[{"count":3,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts\/10728\/revisions"}],"predecessor-version":[{"id":10844,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/posts\/10728\/revisions\/10844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/media\/10740"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/media?parent=10728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/categories?post=10728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/tags?post=10728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}