{"id":46,"date":"2018-04-25T14:39:05","date_gmt":"2018-04-25T14:39:05","guid":{"rendered":"http:\/\/omaha.cwesites.com\/?page_id=46"},"modified":"2025-11-17T09:44:28","modified_gmt":"2025-11-17T15:44:28","slug":"school-events","status":"publish","type":"page","link":"https:\/\/completewedo.com\/rochester\/school-events\/","title":{"rendered":"School Events"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":10469,"parent":0,"menu_order":24,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-46","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rochester School Events | Complete Weddings + Events<\/title>\n<meta name=\"description\" content=\"DJs for dances, videographers, photographers and photo booths for Fun Days- Complete will help you throw the best school party in Rochester.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/rochester\/school-events\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rochester School Events | Complete Weddings + Events\" \/>\n<meta property=\"og:description\" content=\"DJs for dances, videographers, photographers and photo booths for Fun Days- Complete will help you throw the best school party in Rochester.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/rochester\/school-events\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Rochester\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompleteRochester\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T15:44:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/08\/637287e8-ef1f-4976-9599-890dfae48336.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rochester School Events | Complete Weddings + Events","description":"DJs for dances, videographers, photographers and photo booths for Fun Days- Complete will help you throw the best school party in Rochester.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/rochester\/school-events\/","og_locale":"en_US","og_type":"article","og_title":"Rochester School Events | Complete Weddings + Events","og_description":"DJs for dances, videographers, photographers and photo booths for Fun Days- Complete will help you throw the best school party in Rochester.","og_url":"https:\/\/completewedo.com\/rochester\/school-events\/","og_site_name":"Complete Weddings + Events Rochester","article_publisher":"https:\/\/www.facebook.com\/CompleteRochester\/","article_modified_time":"2025-11-17T15:44:28+00:00","og_image":[{"width":1800,"height":849,"url":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/08\/637287e8-ef1f-4976-9599-890dfae48336.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/completewedo.com\/rochester\/school-events\/","url":"https:\/\/completewedo.com\/rochester\/school-events\/","name":"Rochester School Events | Complete Weddings + Events","isPartOf":{"@id":"https:\/\/completewedo.com\/rochester\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/rochester\/school-events\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/rochester\/school-events\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/08\/637287e8-ef1f-4976-9599-890dfae48336.jpg","datePublished":"2018-04-25T14:39:05+00:00","dateModified":"2025-11-17T15:44:28+00:00","description":"DJs for dances, videographers, photographers and photo booths for Fun Days- Complete will help you throw the best school party in Rochester.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/rochester\/school-events\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/rochester\/school-events\/#primaryimage","url":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/08\/637287e8-ef1f-4976-9599-890dfae48336.jpg","contentUrl":"https:\/\/completewedo.com\/rochester\/wp-content\/uploads\/sites\/169\/2019\/08\/637287e8-ef1f-4976-9599-890dfae48336.jpg","width":1800,"height":849,"caption":"School Events"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/rochester\/#website","url":"https:\/\/completewedo.com\/rochester\/","name":"Complete Weddings + Events Rochester","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/rochester\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/pages\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":11,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/pages\/46\/revisions"}],"predecessor-version":[{"id":14000,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/pages\/46\/revisions\/14000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/media\/10469"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/rochester\/wp-json\/wp\/v2\/media?parent=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}