{"id":10698,"date":"2025-05-19T14:10:47","date_gmt":"2025-05-19T14:10:47","guid":{"rendered":"https:\/\/completewedo.com\/new-york-city-new\/?page_id=10698"},"modified":"2025-06-19T17:39:00","modified_gmt":"2025-06-19T17:39:00","slug":"our-culture","status":"publish","type":"page","link":"https:\/\/completewedo.com\/new-york-city\/our-culture\/","title":{"rendered":"Our Culture"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":99,"featured_media":10814,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10698","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our Culture | Complete Weddings + Events New York City<\/title>\n<meta name=\"description\" content=\"Happy employees equal happy customers. It\u2019s the Complete (Wedding + Events) picture. Discover our culture at Complete Weddings + Events.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/new-york-city\/our-culture\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our Culture | Complete Weddings + Events New York City\" \/>\n<meta property=\"og:description\" content=\"Happy employees equal happy customers. It\u2019s the Complete (Wedding + Events) picture. Discover our culture at Complete Weddings + Events.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/new-york-city\/our-culture\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events New York City\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/completeomaha\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T17:39:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/completewedo.com\/new-york-city\/wp-content\/uploads\/sites\/183\/2025\/06\/A86A0797copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our Culture | Complete Weddings + Events New York City","description":"Happy employees equal happy customers. It\u2019s the Complete (Wedding + Events) picture. Discover our culture at Complete Weddings + Events.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/new-york-city\/our-culture\/","og_locale":"en_US","og_type":"article","og_title":"Our Culture | Complete Weddings + Events New York City","og_description":"Happy employees equal happy customers. It\u2019s the Complete (Wedding + Events) picture. Discover our culture at Complete Weddings + Events.","og_url":"https:\/\/completewedo.com\/new-york-city\/our-culture\/","og_site_name":"Complete Weddings + Events New York City","article_publisher":"http:\/\/facebook.com\/completeomaha\/","article_modified_time":"2025-06-19T17:39:00+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/completewedo.com\/new-york-city\/wp-content\/uploads\/sites\/183\/2025\/06\/A86A0797copy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/completewedo.com\/new-york-city\/our-culture\/","url":"https:\/\/completewedo.com\/new-york-city\/our-culture\/","name":"Our Culture | Complete Weddings + Events New York City","isPartOf":{"@id":"https:\/\/completewedo.com\/new-york-city\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/new-york-city\/our-culture\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/new-york-city\/our-culture\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/new-york-city\/wp-content\/uploads\/sites\/183\/2025\/06\/A86A0797copy.jpg","datePublished":"2025-05-19T14:10:47+00:00","dateModified":"2025-06-19T17:39:00+00:00","description":"Happy employees equal happy customers. It\u2019s the Complete (Wedding + Events) picture. Discover our culture at Complete Weddings + Events.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/new-york-city\/our-culture\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/new-york-city\/our-culture\/#primaryimage","url":"https:\/\/completewedo.com\/new-york-city\/wp-content\/uploads\/sites\/183\/2025\/06\/A86A0797copy.jpg","contentUrl":"https:\/\/completewedo.com\/new-york-city\/wp-content\/uploads\/sites\/183\/2025\/06\/A86A0797copy.jpg","width":1000,"height":667,"caption":"Our Culture"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/new-york-city\/#website","url":"https:\/\/completewedo.com\/new-york-city\/","name":"Complete Weddings + Events New York City","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/new-york-city\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/pages\/10698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/comments?post=10698"}],"version-history":[{"count":6,"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/pages\/10698\/revisions"}],"predecessor-version":[{"id":10825,"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/pages\/10698\/revisions\/10825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/media\/10814"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/new-york-city\/wp-json\/wp\/v2\/media?parent=10698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}