{"id":14541,"date":"2024-01-25T23:52:51","date_gmt":"2024-01-25T23:52:51","guid":{"rendered":"https:\/\/completewedo.com\/indianapolis-new\/?p=14541"},"modified":"2026-06-10T21:04:08","modified_gmt":"2026-06-10T21:04:08","slug":"kristen-matts-ivory-foundry-wedding","status":"publish","type":"post","link":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/","title":{"rendered":"Kristen + Matt\u2019s Ivory Foundry Wedding"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Love and style in one of Indianapolis\u2019s best wedding venues: <a href=\"https:\/\/www.ivoryfoundryevents.com\/\" target=\"_blank\" rel=\"noopener\">The Ivory Foundry<\/a>. Kristen and Matt recently tied the knot and celebrated with family at this downtown venue with lots of character. The venue with its plethora of windows, exposed natural wood beam ceiling, textured concrete walls, and exterior murals is perfect for any couple! Keep scrolling as we dive into more of this Ivory Foundry Wedding.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Love and style in one of Indianapolis\u2019s best wedding venues: The Ivory Foundry. Kristen and Matt recently tied the knot and celebrated with family at this downtown venue with lots of character. The venue with its plethora of windows, exposed natural wood beam ceiling, textured concrete walls, and exterior murals is perfect for any couple! [&hellip;]<\/p>\n","protected":false},"author":99,"featured_media":14554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-14541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weddings-engagements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kristen + Matt\u2019s Ivory Foundry Wedding | Indianapolis, IN<\/title>\n<meta name=\"description\" content=\"Kristen and Matt recently held their wedding reception at one of Indy&#039;s best venues! Click here to see more from their Ivory Foundry wedding.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kristen + Matt\u2019s Ivory Foundry Wedding | Indianapolis, IN\" \/>\n<meta property=\"og:description\" content=\"Kristen and Matt recently held their wedding reception at one of Indy&#039;s best venues! Click here to see more from their Ivory Foundry wedding.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Indianapolis\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/completeomaha\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T23:52:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T21:04:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/completewedo.com\/indianapolis\/wp-content\/uploads\/sites\/152\/2024\/01\/Gring_R-4051-blogcover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"completezahira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"completezahira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kristen + Matt\u2019s Ivory Foundry Wedding | Indianapolis, IN","description":"Kristen and Matt recently held their wedding reception at one of Indy's best venues! Click here to see more from their Ivory Foundry wedding.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/","og_locale":"en_US","og_type":"article","og_title":"Kristen + Matt\u2019s Ivory Foundry Wedding | Indianapolis, IN","og_description":"Kristen and Matt recently held their wedding reception at one of Indy's best venues! Click here to see more from their Ivory Foundry wedding.","og_url":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/","og_site_name":"Complete Weddings + Events Indianapolis","article_publisher":"http:\/\/facebook.com\/completeomaha\/","article_published_time":"2024-01-25T23:52:51+00:00","article_modified_time":"2026-06-10T21:04:08+00:00","og_image":[{"width":1200,"height":800,"url":"http:\/\/completewedo.com\/indianapolis\/wp-content\/uploads\/sites\/152\/2024\/01\/Gring_R-4051-blogcover.jpg","type":"image\/jpeg"}],"author":"completezahira","twitter_card":"summary_large_image","twitter_misc":{"Written by":"completezahira","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/#article","isPartOf":{"@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/"},"author":{"name":"completezahira","@id":"https:\/\/completewedo.com\/indianapolis\/#\/schema\/person\/69931f2a23b322c06a4dd55ea1427bed"},"headline":"Kristen + Matt\u2019s Ivory Foundry Wedding","datePublished":"2024-01-25T23:52:51+00:00","dateModified":"2026-06-10T21:04:08+00:00","mainEntityOfPage":{"@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/"},"wordCount":74,"image":{"@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/indianapolis\/wp-content\/uploads\/sites\/152\/2024\/01\/Gring_R-4051-blogcover.jpg","articleSection":["Weddings &amp; Engagements"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/","url":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/","name":"Kristen + Matt\u2019s Ivory Foundry Wedding | Indianapolis, IN","isPartOf":{"@id":"https:\/\/completewedo.com\/indianapolis\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/indianapolis\/wp-content\/uploads\/sites\/152\/2024\/01\/Gring_R-4051-blogcover.jpg","datePublished":"2024-01-25T23:52:51+00:00","dateModified":"2026-06-10T21:04:08+00:00","author":{"@id":"https:\/\/completewedo.com\/indianapolis\/#\/schema\/person\/69931f2a23b322c06a4dd55ea1427bed"},"description":"Kristen and Matt recently held their wedding reception at one of Indy's best venues! Click here to see more from their Ivory Foundry wedding.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/indianapolis\/blog\/kristen-matts-ivory-foundry-wedding\/#primaryimage","url":"https:\/\/completewedo.com\/indianapolis\/wp-content\/uploads\/sites\/152\/2024\/01\/Gring_R-4051-blogcover.jpg","contentUrl":"https:\/\/completewedo.com\/indianapolis\/wp-content\/uploads\/sites\/152\/2024\/01\/Gring_R-4051-blogcover.jpg","width":1200,"height":800,"caption":"Ivory Foundry wedding"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/indianapolis\/#website","url":"https:\/\/completewedo.com\/indianapolis\/","name":"Complete Weddings + Events Indianapolis","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/indianapolis\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/completewedo.com\/indianapolis\/#\/schema\/person\/69931f2a23b322c06a4dd55ea1427bed","name":"completezahira","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ad2366e359d86d978c884881b530c2c1773e0b76f889d5fdfd084b5fc2b8946f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ad2366e359d86d978c884881b530c2c1773e0b76f889d5fdfd084b5fc2b8946f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ad2366e359d86d978c884881b530c2c1773e0b76f889d5fdfd084b5fc2b8946f?s=96&d=mm&r=g","caption":"completezahira"},"url":"https:\/\/completewedo.com\/indianapolis\/blog\/author\/completezahira\/"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/posts\/14541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/comments?post=14541"}],"version-history":[{"count":7,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/posts\/14541\/revisions"}],"predecessor-version":[{"id":16415,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/posts\/14541\/revisions\/16415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/media\/14554"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/media?parent=14541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/categories?post=14541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/completewedo.com\/indianapolis\/wp-json\/wp\/v2\/tags?post=14541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}