{"id":18473,"date":"2022-12-02T21:24:14","date_gmt":"2022-12-02T21:24:14","guid":{"rendered":"https:\/\/completewedo.com\/fort-lauderdale-new\/?p=18473"},"modified":"2026-07-06T17:04:33","modified_gmt":"2026-07-06T17:04:33","slug":"meet-dj-ike","status":"publish","type":"post","link":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/","title":{"rendered":"Meet DJ Ike"},"content":{"rendered":"<h3>Seven Words That Describe Me<\/h3>\n<p>Outgoing, Respectful, Friendly, Ambitious, Energetic, Flexible, Honest<\/p>\n<h3>My Relationship With Music<\/h3>\n<p>Music is a huge part of my everyday life! It helps me relax when times are tough! It helps me set the mood for any environment. Music pushes my mind and body to the maximum! Music gives me the space to forget about the outside world and just feel free! Music has given me the motivation to move to places like Las Vegas &amp; LA to study The industry of Entertainment!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seven Words That Describe Me Outgoing, Respectful, Friendly, Ambitious, Energetic, Flexible, Honest My Relationship With Music Music is a huge part of my everyday life! It helps me relax when times are tough! It helps me set the mood for any environment. Music pushes my mind and body to the maximum! Music gives me the [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":18486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-18473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dj"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meet DJ Ike | Complete Weddings + Events Fort Lauderdale, FL<\/title>\n<meta name=\"description\" content=\"Meet DJ Ike - A Fort Lauderdale DJ with Complete Weddings + Events. Ike loves to make a crowd dance and put a smile on everyone&#039;s face.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meet DJ Ike | Complete Weddings + Events Fort Lauderdale, FL\" \/>\n<meta property=\"og:description\" content=\"Meet DJ Ike - A Fort Lauderdale DJ with Complete Weddings + Events. Ike loves to make a crowd dance and put a smile on everyone&#039;s face.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Fort Lauderdale\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/completeomaha\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/CompleteWeddingsSouthFlorida\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-02T21:24:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T17:04:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/completewedo.com\/fort-lauderdale\/wp-content\/uploads\/sites\/149\/2022\/12\/Meet-DJ-Ike-1800x1013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fortlauderdaleadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CompleteMedia2\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"fortlauderdaleadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meet DJ Ike | Complete Weddings + Events Fort Lauderdale, FL","description":"Meet DJ Ike - A Fort Lauderdale DJ with Complete Weddings + Events. Ike loves to make a crowd dance and put a smile on everyone's face.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/","og_locale":"en_US","og_type":"article","og_title":"Meet DJ Ike | Complete Weddings + Events Fort Lauderdale, FL","og_description":"Meet DJ Ike - A Fort Lauderdale DJ with Complete Weddings + Events. Ike loves to make a crowd dance and put a smile on everyone's face.","og_url":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/","og_site_name":"Complete Weddings + Events Fort Lauderdale","article_publisher":"http:\/\/facebook.com\/completeomaha\/","article_author":"https:\/\/www.facebook.com\/CompleteWeddingsSouthFlorida","article_published_time":"2022-12-02T21:24:14+00:00","article_modified_time":"2026-07-06T17:04:33+00:00","og_image":[{"width":2560,"height":1440,"url":"http:\/\/completewedo.com\/fort-lauderdale\/wp-content\/uploads\/sites\/149\/2022\/12\/Meet-DJ-Ike-1800x1013.jpg","type":"image\/jpeg"}],"author":"fortlauderdaleadmin","twitter_card":"summary_large_image","twitter_creator":"@CompleteMedia2","twitter_misc":{"Written by":"fortlauderdaleadmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/#article","isPartOf":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/"},"author":{"name":"fortlauderdaleadmin","@id":"https:\/\/completewedo.com\/fort-lauderdale\/#\/schema\/person\/a07a6bb5bb2b0c3e5824b835f17888d9"},"headline":"Meet DJ Ike","datePublished":"2022-12-02T21:24:14+00:00","dateModified":"2026-07-06T17:04:33+00:00","mainEntityOfPage":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/"},"wordCount":90,"image":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/fort-lauderdale\/wp-content\/uploads\/sites\/149\/2022\/12\/Meet-DJ-Ike-1800x1013.jpg","articleSection":["Disc Jockey"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/","url":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/","name":"Meet DJ Ike | Complete Weddings + Events Fort Lauderdale, FL","isPartOf":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/fort-lauderdale\/wp-content\/uploads\/sites\/149\/2022\/12\/Meet-DJ-Ike-1800x1013.jpg","datePublished":"2022-12-02T21:24:14+00:00","dateModified":"2026-07-06T17:04:33+00:00","author":{"@id":"https:\/\/completewedo.com\/fort-lauderdale\/#\/schema\/person\/a07a6bb5bb2b0c3e5824b835f17888d9"},"description":"Meet DJ Ike - A Fort Lauderdale DJ with Complete Weddings + Events. Ike loves to make a crowd dance and put a smile on everyone's face.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/meet-dj-ike\/#primaryimage","url":"https:\/\/completewedo.com\/fort-lauderdale\/wp-content\/uploads\/sites\/149\/2022\/12\/Meet-DJ-Ike-1800x1013.jpg","contentUrl":"https:\/\/completewedo.com\/fort-lauderdale\/wp-content\/uploads\/sites\/149\/2022\/12\/Meet-DJ-Ike-1800x1013.jpg","width":2560,"height":1440,"caption":"Meet DJ Ike"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/fort-lauderdale\/#website","url":"https:\/\/completewedo.com\/fort-lauderdale\/","name":"Complete Weddings + Events Fort Lauderdale","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/fort-lauderdale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/completewedo.com\/fort-lauderdale\/#\/schema\/person\/a07a6bb5bb2b0c3e5824b835f17888d9","name":"fortlauderdaleadmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b239daa9da0dea7e26bea68d675b8b4cb8c550328b339343ce507a7059dd4bb8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b239daa9da0dea7e26bea68d675b8b4cb8c550328b339343ce507a7059dd4bb8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b239daa9da0dea7e26bea68d675b8b4cb8c550328b339343ce507a7059dd4bb8?s=96&d=mm&r=g","caption":"fortlauderdaleadmin"},"sameAs":["https:\/\/www.facebook.com\/CompleteWeddingsSouthFlorida","https:\/\/www.instagram.com\/completeMVP","https:\/\/www.pinterest.com\/completemediasf","https:\/\/x.com\/CompleteMedia2","https:\/\/tinyurl.com\/y9h36nfk"],"url":"https:\/\/completewedo.com\/fort-lauderdale\/blog\/author\/fortlauderdaleadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/posts\/18473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/comments?post=18473"}],"version-history":[{"count":10,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/posts\/18473\/revisions"}],"predecessor-version":[{"id":18487,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/posts\/18473\/revisions\/18487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/media\/18486"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/media?parent=18473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/categories?post=18473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/completewedo.com\/fort-lauderdale\/wp-json\/wp\/v2\/tags?post=18473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}