{"id":15674,"date":"2023-07-05T08:00:42","date_gmt":"2023-07-05T13:00:42","guid":{"rendered":"https:\/\/completewedo.com\/central-illinois-new\/?p=15674"},"modified":"2023-06-16T10:36:46","modified_gmt":"2023-06-16T15:36:46","slug":"jordan-and-libbis-proposal-story-complete-weddings-events-owners","status":"publish","type":"post","link":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/","title":{"rendered":"Jordan and Libbi&#8217;s Proposal Story &#8211; Complete Weddings + Events Owners"},"content":{"rendered":"<p>We know, we know&#8230;you didn&#8217;t come here to learn about the Complete Weddings + Events owners. You came here to learn about our services and get a little inspiration when planning your wedding. However, there&#8217;s one key moment that happens BEFORE the wedding, and that&#8217;s the proposal. After chatting with some of our peers, we thought it might be fun to share our proposal story with you all. At the very least, you can always send this info to your significant other if you&#8217;re hoping he\/she pops the question soon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>We know, we know&#8230;you didn&#8217;t come here to learn about the Complete Weddings + Events owners. You came here to learn about our services and get a little inspiration when planning your wedding. However, there&#8217;s one key moment that happens BEFORE the wedding, and that&#8217;s the proposal. After chatting with some of our peers, we [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":15679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,9,11],"tags":[],"class_list":["post-15674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration","category-photography","category-weddings-engagements"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jordan and Libbi&#039;s Proposal Story - Complete Weddings + Events<\/title>\n<meta name=\"description\" content=\"Jordan proposed to Libbi at the Palms in Miami, FL. Read about Jordan and Libbi&#039;s proposal story and view photos from the magical evening.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jordan and Libbi&#039;s Proposal Story - Complete Weddings + Events\" \/>\n<meta property=\"og:description\" content=\"Jordan proposed to Libbi at the Palms in Miami, FL. Read about Jordan and Libbi&#039;s proposal story and view photos from the magical evening.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Central Illinois\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/completeomaha\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-05T13:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/completewedo.com\/central-illinois\/wp-content\/uploads\/sites\/136\/2023\/06\/Proposal1Compressed-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"stladmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"stladmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jordan and Libbi's Proposal Story - Complete Weddings + Events","description":"Jordan proposed to Libbi at the Palms in Miami, FL. Read about Jordan and Libbi's proposal story and view photos from the magical evening.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/","og_locale":"en_US","og_type":"article","og_title":"Jordan and Libbi's Proposal Story - Complete Weddings + Events","og_description":"Jordan proposed to Libbi at the Palms in Miami, FL. Read about Jordan and Libbi's proposal story and view photos from the magical evening.","og_url":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/","og_site_name":"Complete Weddings + Events Central Illinois","article_publisher":"http:\/\/facebook.com\/completeomaha\/","article_published_time":"2023-07-05T13:00:42+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/completewedo.com\/central-illinois\/wp-content\/uploads\/sites\/136\/2023\/06\/Proposal1Compressed-scaled.jpg","type":"image\/jpeg"}],"author":"stladmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"stladmin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/#article","isPartOf":{"@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/"},"author":{"name":"stladmin","@id":"https:\/\/completewedo.com\/central-illinois\/#\/schema\/person\/0186b447a4f0b9d761e1ed80015a22cb"},"headline":"Jordan and Libbi&#8217;s Proposal Story &#8211; Complete Weddings + Events Owners","datePublished":"2023-07-05T13:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/"},"wordCount":106,"commentCount":0,"image":{"@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/central-illinois\/wp-content\/uploads\/sites\/136\/2023\/06\/Proposal1Compressed-scaled.jpg","articleSection":["Inspiration","Photography","Weddings &amp; Engagements"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/","url":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/","name":"Jordan and Libbi's Proposal Story - Complete Weddings + Events","isPartOf":{"@id":"https:\/\/completewedo.com\/central-illinois\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/central-illinois\/wp-content\/uploads\/sites\/136\/2023\/06\/Proposal1Compressed-scaled.jpg","datePublished":"2023-07-05T13:00:42+00:00","author":{"@id":"https:\/\/completewedo.com\/central-illinois\/#\/schema\/person\/0186b447a4f0b9d761e1ed80015a22cb"},"description":"Jordan proposed to Libbi at the Palms in Miami, FL. Read about Jordan and Libbi's proposal story and view photos from the magical evening.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/central-illinois\/blog\/jordan-and-libbis-proposal-story-complete-weddings-events-owners\/#primaryimage","url":"https:\/\/completewedo.com\/central-illinois\/wp-content\/uploads\/sites\/136\/2023\/06\/Proposal1Compressed-scaled.jpg","contentUrl":"https:\/\/completewedo.com\/central-illinois\/wp-content\/uploads\/sites\/136\/2023\/06\/Proposal1Compressed-scaled.jpg","width":2560,"height":1707,"caption":"Jordan and Libbi's Proposal Story"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/central-illinois\/#website","url":"https:\/\/completewedo.com\/central-illinois\/","name":"Complete Weddings + Events Central Illinois","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/central-illinois\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/completewedo.com\/central-illinois\/#\/schema\/person\/0186b447a4f0b9d761e1ed80015a22cb","name":"stladmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/11d93a6874c7737b9a7f14e6be778cb7bc4eec8749b30a476d337bfdd7491bf7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/11d93a6874c7737b9a7f14e6be778cb7bc4eec8749b30a476d337bfdd7491bf7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/11d93a6874c7737b9a7f14e6be778cb7bc4eec8749b30a476d337bfdd7491bf7?s=96&d=mm&r=g","caption":"stladmin"},"url":"https:\/\/completewedo.com\/central-illinois\/blog\/author\/stladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/posts\/15674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/comments?post=15674"}],"version-history":[{"count":10,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/posts\/15674\/revisions"}],"predecessor-version":[{"id":15770,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/posts\/15674\/revisions\/15770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/media\/15679"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/media?parent=15674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/categories?post=15674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/completewedo.com\/central-illinois\/wp-json\/wp\/v2\/tags?post=15674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}