{"id":10638,"date":"2020-11-02T15:28:56","date_gmt":"2020-11-02T15:28:56","guid":{"rendered":"https:\/\/completewedo.com\/brainerd-new\/?p=10638"},"modified":"2020-11-02T15:28:56","modified_gmt":"2020-11-02T15:28:56","slug":"do-good-together-2020","status":"publish","type":"post","link":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/","title":{"rendered":"Do Good Together 2020"},"content":{"rendered":"<p>Complete Weddings + Events\u2019 annual Do Good Together fundraising campaign is back! During the month of October, when you choose Complete Weddings + Events for DJ, photography, videography, uplighting, or photo booth, 3% of your package goes to an important cause. We promise this is something worth partying for!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Complete Weddings + Events\u2019 annual Do Good Together fundraising campaign is back! During the month of October, when you choose Complete Weddings + Events for DJ, photography, videography, uplighting, or photo booth, 3% of your package goes to an important cause. We promise this is something worth partying for!<\/p>\n","protected":false},"author":62,"featured_media":10657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Do Good Together 2020 - Complete Weddings + Events Brainerd<\/title>\n<meta name=\"description\" content=\"Do Good Together 2020: The program will provide an alternative educational pathway for kids and young adults struggling to succeed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Do Good Together 2020 - Complete Weddings + Events Brainerd\" \/>\n<meta property=\"og:description\" content=\"Do Good Together 2020: The program will provide an alternative educational pathway for kids and young adults struggling to succeed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Complete Weddings + Events Brainerd\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/completeomaha\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T15:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/completewedo.com\/brainerd\/wp-content\/uploads\/sites\/167\/2020\/10\/do-good-together-10-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rochesteradmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rochesteradmin\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Do Good Together 2020 - Complete Weddings + Events Brainerd","description":"Do Good Together 2020: The program will provide an alternative educational pathway for kids and young adults struggling to succeed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/","og_locale":"en_US","og_type":"article","og_title":"Do Good Together 2020 - Complete Weddings + Events Brainerd","og_description":"Do Good Together 2020: The program will provide an alternative educational pathway for kids and young adults struggling to succeed.","og_url":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/","og_site_name":"Complete Weddings + Events Brainerd","article_publisher":"http:\/\/facebook.com\/completeomaha\/","article_published_time":"2020-11-02T15:28:56+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/completewedo.com\/brainerd\/wp-content\/uploads\/sites\/167\/2020\/10\/do-good-together-10-1.jpg","type":"image\/jpeg"}],"author":"rochesteradmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"rochesteradmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/#article","isPartOf":{"@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/"},"author":{"name":"rochesteradmin","@id":"https:\/\/completewedo.com\/brainerd\/#\/schema\/person\/605d46bc36541b56b9f486fba3a1f6e2"},"headline":"Do Good Together 2020","datePublished":"2020-11-02T15:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/"},"wordCount":49,"image":{"@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/brainerd\/wp-content\/uploads\/sites\/167\/2020\/10\/do-good-together-10-1.jpg","articleSection":["Inspiration"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/","url":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/","name":"Do Good Together 2020 - Complete Weddings + Events Brainerd","isPartOf":{"@id":"https:\/\/completewedo.com\/brainerd\/#website"},"primaryImageOfPage":{"@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/#primaryimage"},"image":{"@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/completewedo.com\/brainerd\/wp-content\/uploads\/sites\/167\/2020\/10\/do-good-together-10-1.jpg","datePublished":"2020-11-02T15:28:56+00:00","author":{"@id":"https:\/\/completewedo.com\/brainerd\/#\/schema\/person\/605d46bc36541b56b9f486fba3a1f6e2"},"description":"Do Good Together 2020: The program will provide an alternative educational pathway for kids and young adults struggling to succeed.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/completewedo.com\/brainerd\/blog\/do-good-together-2020\/#primaryimage","url":"https:\/\/completewedo.com\/brainerd\/wp-content\/uploads\/sites\/167\/2020\/10\/do-good-together-10-1.jpg","contentUrl":"https:\/\/completewedo.com\/brainerd\/wp-content\/uploads\/sites\/167\/2020\/10\/do-good-together-10-1.jpg","width":720,"height":720,"caption":"Do Good Together 2020"},{"@type":"WebSite","@id":"https:\/\/completewedo.com\/brainerd\/#website","url":"https:\/\/completewedo.com\/brainerd\/","name":"Complete Weddings + Events Brainerd","description":"Photography | Videography | Photo Booth | Lighting | DJ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/completewedo.com\/brainerd\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/completewedo.com\/brainerd\/#\/schema\/person\/605d46bc36541b56b9f486fba3a1f6e2","name":"rochesteradmin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/890613dc55a291979e438fb146106554f32353afbdb3955e393d3bab500e2449?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/890613dc55a291979e438fb146106554f32353afbdb3955e393d3bab500e2449?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/890613dc55a291979e438fb146106554f32353afbdb3955e393d3bab500e2449?s=96&d=mm&r=g","caption":"rochesteradmin"},"url":"https:\/\/completewedo.com\/brainerd\/blog\/author\/rochesteradmin\/"}]}},"_links":{"self":[{"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/posts\/10638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/comments?post=10638"}],"version-history":[{"count":6,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/posts\/10638\/revisions"}],"predecessor-version":[{"id":10665,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/posts\/10638\/revisions\/10665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/media\/10657"}],"wp:attachment":[{"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/media?parent=10638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/categories?post=10638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/completewedo.com\/brainerd\/wp-json\/wp\/v2\/tags?post=10638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}